  {"id":5,"date":"2014-05-21T14:25:41","date_gmt":"2014-05-21T18:25:41","guid":{"rendered":"http:\/\/www.ramapo.edu\/international-travel\/?page_id=5"},"modified":"2022-04-01T14:01:47","modified_gmt":"2022-04-01T18:01:47","slug":"home","status":"publish","type":"page","link":"https:\/\/www.ramapo.edu\/international-travel\/","title":{"rendered":"Home"},"content":{"rendered":"<div class=\"infoBox col-sm-12 col-lg-12  goldBox\" style=\"float: none; margin: 0 auto;\"><div class=\"boxTitle\">COVID-19 Resources<\/div><div class=\"boxContent\">\n<p><a href=\"https:\/\/www.ramapo.edu\/international-travel\/resources\/health\/covid-19\/\" target=\"_blank\" rel=\"noopener noreferrer\">COVID-19 Resources<\/a> <em>(Travel, General, International, State, etc.)<\/em><\/p>\n<\/div><\/div>\n<p>The 69色情视频 International Travel Policy &amp; Procedures applies to all official international travel of all 69色情视频\u00a0employees\u00a0and students, regardless of funding.\u00a0\u00a0Official College\u00a0travel includes, but is not limited to travel for: conferences, research, sabbatical, guest scholarship, partnership collaboration and development, or class credit.\u00a0\u00a0This policy does not apply to personal travel.<\/p>\n<p><strong>What is considered Official College Travel?<\/strong><\/p>\n<p>Official College travel includes all international and domestic travel by faculty or staff and other eligible participants, which is organized, approved, administered, or funded by the College or by the 69色情视频 Foundation, or external funders. Examples of these activities include: Faculty\/staff-led programs; recruitment trips; program assessment trips; conference attendance; scholarly capacity; etc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The 69色情视频 International Travel Policy &amp; Procedures applies to all official international travel of all 69色情视频\u00a0employees\u00a0and students, regardless of funding.\u00a0\u00a0Official College\u00a0travel includes, but is not limited to travel for: conferences, research, sabbatical, guest scholarship, partnership collaboration and development, or class credit.\u00a0\u00a0This policy does not apply to personal travel. What is considered Official College [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"page_leftCol_header.php","meta":{"footnotes":""},"class_list":["post-5","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Home - International Travel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ramapo.edu\/international-travel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home\" \/>\n<meta property=\"og:description\" content=\"The 69色情视频 International Travel Policy &amp; Procedures applies to all official international travel of all 69色情视频\u00a0employees\u00a0and students, regardless of funding.\u00a0\u00a0Official College\u00a0travel includes, but is not limited to travel for: conferences, research, sabbatical, guest scholarship, partnership collaboration and development, or class credit.\u00a0\u00a0This policy does not apply to personal travel. What is considered Official College [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ramapo.edu\/international-travel\/\" \/>\n<meta property=\"og:site_name\" content=\"International Travel\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-01T18:01:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ramapo.edu\\\/international-travel\\\/\",\"url\":\"https:\\\/\\\/www.ramapo.edu\\\/international-travel\\\/\",\"name\":\"Home - International Travel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ramapo.edu\\\/international-travel\\\/#website\"},\"datePublished\":\"2014-05-21T18:25:41+00:00\",\"dateModified\":\"2022-04-01T18:01:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ramapo.edu\\\/international-travel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ramapo.edu\\\/international-travel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ramapo.edu\\\/international-travel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"69色情视频 of New Jersey Home Page \u00bb Ramapo International \u00bb International Travel\",\"item\":\"https:\\\/\\\/www.ramapo.edu\\\/international-travel\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ramapo.edu\\\/international-travel\\\/#website\",\"url\":\"https:\\\/\\\/www.ramapo.edu\\\/international-travel\\\/\",\"name\":\"International Travel\",\"description\":\"Just another 69色情视频 of New Jersey Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ramapo.edu\\\/international-travel\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Home - International Travel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ramapo.edu\/international-travel\/","og_locale":"en_US","og_type":"article","og_title":"Home","og_description":"The 69色情视频 International Travel Policy &amp; Procedures applies to all official international travel of all 69色情视频\u00a0employees\u00a0and students, regardless of funding.\u00a0\u00a0Official College\u00a0travel includes, but is not limited to travel for: conferences, research, sabbatical, guest scholarship, partnership collaboration and development, or class credit.\u00a0\u00a0This policy does not apply to personal travel. What is considered Official College [&hellip;]","og_url":"https:\/\/www.ramapo.edu\/international-travel\/","og_site_name":"International Travel","article_modified_time":"2022-04-01T18:01:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ramapo.edu\/international-travel\/","url":"https:\/\/www.ramapo.edu\/international-travel\/","name":"Home - International Travel","isPartOf":{"@id":"https:\/\/www.ramapo.edu\/international-travel\/#website"},"datePublished":"2014-05-21T18:25:41+00:00","dateModified":"2022-04-01T18:01:47+00:00","breadcrumb":{"@id":"https:\/\/www.ramapo.edu\/international-travel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ramapo.edu\/international-travel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ramapo.edu\/international-travel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"69色情视频 of New Jersey Home Page \u00bb Ramapo International \u00bb International Travel","item":"https:\/\/www.ramapo.edu\/international-travel\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/www.ramapo.edu\/international-travel\/#website","url":"https:\/\/www.ramapo.edu\/international-travel\/","name":"International Travel","description":"Just another 69色情视频 of New Jersey Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ramapo.edu\/international-travel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.ramapo.edu\/international-travel\/wp-json\/wp\/v2\/pages\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ramapo.edu\/international-travel\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ramapo.edu\/international-travel\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ramapo.edu\/international-travel\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ramapo.edu\/international-travel\/wp-json\/wp\/v2\/comments?post=5"}],"version-history":[{"count":20,"href":"https:\/\/www.ramapo.edu\/international-travel\/wp-json\/wp\/v2\/pages\/5\/revisions"}],"predecessor-version":[{"id":539,"href":"https:\/\/www.ramapo.edu\/international-travel\/wp-json\/wp\/v2\/pages\/5\/revisions\/539"}],"wp:attachment":[{"href":"https:\/\/www.ramapo.edu\/international-travel\/wp-json\/wp\/v2\/media?parent=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}